{"id":283443,"date":"2022-06-10T10:00:00","date_gmt":"2022-06-10T13:00:00","guid":{"rendered":"https:\/\/wordpress.instacarro.com\/?p=283443"},"modified":"2022-06-10T10:00:00","modified_gmt":"2022-06-10T13:00:00","slug":"replica-de-carros","status":"publish","type":"post","link":"https:\/\/www.instacarro.com\/blog\/documentacao-e-legislacao-veicular\/replica-de-carros","title":{"rendered":"R\u00e9plicas de carros: o que diz a legisla\u00e7\u00e3o"},"content":{"rendered":"\n<p><strong><em>O que diz a legisla\u00e7\u00e3o brasileira quanto \u00e0 produ\u00e7\u00e3o de r\u00e9plicas de carros? O que \u00e9 permitido e o que \u00e9 proibido? Confira tudo aqui!<\/em><\/strong><\/p>\n\n\n\n<p>\u00c9 o sonho de qualquer apaixonado por carros possuir uma super m\u00e1quina. Por\u00e9m, infelizmente, s\u00e3o poucos os que possuem recursos suficientes para comprar modelos como os da <a href=\"https:\/\/instacarro.com\/blog\/noticias\/lamborghini-urus\/\" target=\"_blank\" rel=\"noreferrer noopener\">Lamborghini<\/a> ou <a href=\"https:\/\/instacarro.com\/blog\/noticias\/historia-da-ferrari\/\" target=\"_blank\" rel=\"noreferrer noopener\">Ferrari<\/a>, por exemplo.\u00a0<\/p>\n\n\n\n<p>Mas como diz o ditado popular: \u201co brasileiro sempre d\u00e1 um jeitinho para tudo\u201d. Um desses \u201cjeitinhos\u201d \u00e9 construir r\u00e9plicas desses supercarros. Por\u00e9m, justamente marcas como a Ferrari, ao ver a expans\u00e3o desse mercado, entraram com processos que resultaram no desmantelamento de quadrilhas de falsificadores e na apreens\u00e3o de ve\u00edculos artesanais. <\/p>\n\n\n\n<p>Em contrapartida, h\u00e1 marcas que fazem esse trabalho t\u00e3o bem feito, que as marcas originais autorizam as r\u00e9plicas, como era o caso da brasileira Chamonix (hoje Athos), especializada em r\u00e9plicas de Porsche cl\u00e1ssicos.<\/p>\n\n\n\n<p>Diante disso, muita gente ainda fica com a d\u00favida: ent\u00e3o \u00e9 ou n\u00e3o \u00e9 permitido ter uma r\u00e9plica na garagem?\u00a0<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Pode ou n\u00e3o fazer uma r\u00e9plica de um carro?<\/h2>\n\n\n\n<p>A produ\u00e7\u00e3o de r\u00e9plicas pode infringir a Lei n\u00ba 9.279\/96, que regula os direitos e obriga\u00e7\u00f5es relativos \u00e0 propriedade industrial. O artigo 189 classifica como crime contra registro de marca quem:&nbsp;<\/p>\n\n\n\n<p>I &#8211; reproduz, sem autoriza\u00e7\u00e3o do titular, no todo ou em parte, marca registrada, ou imita-a de modo que possa induzir confus\u00e3o; ou&nbsp;<\/p>\n\n\n\n<p>II &#8211; altera marca registrada de outrem j\u00e1 colocada em produto no mercado.&nbsp;<\/p>\n\n\n\n<p>Inclusive, desrespeitar a lei pode gerar pena de deten\u00e7\u00e3o de 3 meses a um ano, al\u00e9m de uma multa salgada.&nbsp;<\/p>\n\n\n\n<p>O artigo 190 da mesma Lei n\u00ba 9.279\/96 tamb\u00e9m define como crime contra registro de marca &#8220;quem vende, importa, exporta, oferece ou exp\u00f5e \u00e0 venda, oculta ou tem em estoque&#8221;:<\/p>\n\n\n\n<p>I &#8211; produto assinalado com marca ilicitamente reproduzida ou imitada, de outrem, no todo ou em parte; ou&nbsp;<\/p>\n\n\n\n<p>II &#8211; produto de sua ind\u00fastria ou com\u00e9rcio, contido em vasilhame, recipiente ou embalagem que contenha marca leg\u00edtima de outrem.&nbsp;<\/p>\n\n\n\n<p>Neste caso, a pena prevista \u00e9 mais branda, de 1 a 3 meses, ou a aplica\u00e7\u00e3o de uma multa.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Existe alguma lei que permita as r\u00e9plicas?<\/h2>\n\n\n\n<p>A resposta \u00e9 sim! Segundo a resolu\u00e7\u00e3o n\u00ba 597 do Contran, a produ\u00e7\u00e3o de r\u00e9plicas at\u00e9 \u00e9 permitida, por\u00e9m deve seguir algumas normas e para determinados casos:&nbsp;<\/p>\n\n\n\n<p>I &#8211; Fabricantes de Ve\u00edculos de Pequena S\u00e9rie: \u00e9 aquele cuja produ\u00e7\u00e3o est\u00e1 limitada a 30 (trinta) ve\u00edculos por marca\/modelo e 100 (cem) unidades no per\u00edodo de 1\u00ba de janeiro a 31 de dezembro de cada ano;&nbsp;<\/p>\n\n\n\n<p>II &#8211; Fabricantes de Ve\u00edculos Artesanais: \u00e9 a pessoa f\u00edsica ou jur\u00eddica, que fabrica, no m\u00e1ximo, 03 (tr\u00eas) ve\u00edculos no per\u00edodo de 1\u00ba de janeiro a 31 de dezembro de cada ano;&nbsp;<\/p>\n\n\n\n<p>III &#8211; R\u00e9plica \u00e9 o ve\u00edculo produzido por um fabricante de pequena s\u00e9rie e que:&nbsp;<\/p>\n\n\n\n<p>a) assemelha-se a outro ve\u00edculo que foi descontinuado h\u00e1 pelo menos 30 anos;&nbsp;<\/p>\n\n\n\n<p>b) possua licen\u00e7a do fabricante original, seus sucessores ou cession\u00e1rios ou atual propriet\u00e1rio de tais direitos;&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">R\u00e9plicas famosas<\/h2>\n\n\n\n<p>O Brasil possui uma das fabricantes de r\u00e9plicas mais famosas do mundo, a Athos Cars, que come\u00e7ou seu neg\u00f3cio ainda com o nome de Chamonix. Criada em 1987 por Milton Masteguin (fundador da Puma), Chuck Beck e Newton Masteguin, a marca ganhou fama pelo alto n\u00edvel de produ\u00e7\u00e3o de r\u00e9plicas da Porsche.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1280\" height=\"854\" src=\"https:\/\/instacarro.com\/wp-content\/uploads\/2022\/06\/replica-de-carros-porsche-356-1.jpg\" alt=\"replicas de carros - porsche 356\" class=\"wp-image-283444\" title=\"\" srcset=\"https:\/\/www.instacarro.com\/blog\/wp-content\/uploads\/2022\/06\/replica-de-carros-porsche-356-1.jpg 1280w, https:\/\/www.instacarro.com\/blog\/wp-content\/uploads\/2022\/06\/replica-de-carros-porsche-356-1-300x200.jpg 300w, https:\/\/www.instacarro.com\/blog\/wp-content\/uploads\/2022\/06\/replica-de-carros-porsche-356-1-1024x683.jpg 1024w, https:\/\/www.instacarro.com\/blog\/wp-content\/uploads\/2022\/06\/replica-de-carros-porsche-356-1-768x512.jpg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/figure>\n\n\n\n<p>Os pre\u00e7os das r\u00e9plicas n\u00e3o s\u00e3o baratos, custando a partir de R$ 100 mil, dependendo do modelo escolhido. A fama da Athos \u00e9 tanta que at\u00e9 est\u00fadios de cinema costumam usar ve\u00edculos deles. Segundo a empresa, um de seus Porsche 356 aparece no filme &#8220;Ford vs Ferrari&#8221;. O filme venceu dois Oscar nas categorias &#8220;Melhor Edi\u00e7\u00e3o de Som&#8221; e &#8220;Melhor Montagem&#8221;.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Apreens\u00f5es de r\u00e9plicas<\/h2>\n\n\n\n<p>Para a pol\u00edcia, ao contr\u00e1rio da Athos que realiza um trabalho dentro da lei, muitas outras empresas, na verdade, n\u00e3o criam r\u00e9plicas, mas sim falsifica\u00e7\u00f5es. Em 2019, uma den\u00fancia resultou na apreens\u00e3o de quatro ve\u00edculos produzidos em tr\u00eas oficinas em S\u00e3o Paulo.&nbsp;<\/p>\n\n\n\n<p>Logo depois, oito r\u00e9plicas de modelos de Ferrari e Lamborghini foram confiscadas em uma oficina em Santa Catarina. Estima-se que os ve\u00edculos eram vendidos por at\u00e9 R$ 200 mil. Os respons\u00e1veis foram presos por crime contra a propriedade industrial.&nbsp;<\/p>\n\n\n\n<p>Segundo a pol\u00edcia, essas apreens\u00f5es n\u00e3o se tratavam de uma constru\u00e7\u00e3o artesanal de um ve\u00edculo, mas sim da produ\u00e7\u00e3o de um ve\u00edculo com caracter\u00edsticas patenteadas por outras marcas. Nas ocasi\u00f5es citadas, os respons\u00e1veis pelos carros afirmaram que os modelos eram legalizados e tinham at\u00e9 documenta\u00e7\u00e3o regularizada pelo Denatran.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O que diz a legisla\u00e7\u00e3o brasileira quanto \u00e0 produ\u00e7\u00e3o de r\u00e9plicas de carros? O que \u00e9 permitido e o que \u00e9 proibido? Confira tudo aqui!<\/p>\n","protected":false},"author":75,"featured_media":283445,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"class_list":["post-283443","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-documentacao-e-legislacao-veicular"],"_links":{"self":[{"href":"https:\/\/www.instacarro.com\/blog\/wp-json\/wp\/v2\/posts\/283443","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.instacarro.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.instacarro.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.instacarro.com\/blog\/wp-json\/wp\/v2\/users\/75"}],"replies":[{"embeddable":true,"href":"https:\/\/www.instacarro.com\/blog\/wp-json\/wp\/v2\/comments?post=283443"}],"version-history":[{"count":0,"href":"https:\/\/www.instacarro.com\/blog\/wp-json\/wp\/v2\/posts\/283443\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.instacarro.com\/blog\/wp-json\/wp\/v2\/media\/283445"}],"wp:attachment":[{"href":"https:\/\/www.instacarro.com\/blog\/wp-json\/wp\/v2\/media?parent=283443"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.instacarro.com\/blog\/wp-json\/wp\/v2\/categories?post=283443"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.instacarro.com\/blog\/wp-json\/wp\/v2\/tags?post=283443"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}